﻿{"id":241,"date":"2022-11-30T01:26:19","date_gmt":"2022-11-30T00:26:19","guid":{"rendered":"https:\/\/ambwashingtondc.esteri.it\/?page_id=241"},"modified":"2026-05-01T16:14:06","modified_gmt":"2026-05-01T20:14:06","slug":"traduzione-e-legalizzazione-dei-documenti","status":"publish","type":"page","link":"https:\/\/ambwashingtondc.esteri.it\/it\/servizi-consolari-e-visti\/servizi-per-il-cittadino-italiano\/traduzione-e-legalizzazione-dei-documenti\/","title":{"rendered":"Traduzione e legalizzazione dei documenti"},"content":{"rendered":"<p><strong>La nostra Cancelleria Consolare non effettua traduzioni.<\/strong> Spetta in genere agli utenti provvedere autonomamente a tradurre i documenti di loro interesse.<\/p>\n<p>La Cancelleria Consolare tuttavia, provvede a<strong> certificare la conformit\u00e0 agli originali delle traduzioni<\/strong> degli atti di stato civile e di vari altri documenti.<\/p>\n<p>Per un elenco non esclusivo di traduttori e interpreti a cui \u00e8 possibile rivolgersi nell\u2019area di Washington, <a href=\"https:\/\/ambwashingtondc.esteri.it\/it\/servizi-consolari-e-visti\/servizi-per-il-cittadino-italiano\/assistenza-ai-cittadini-allestero\/elenchi-dei-professionisti-di-riferimento-a-disposizione-dellutenza-della-circoscrizione-consolare-di-washington-d-c#traduttori\">clicca qui<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>Per maggiori informazioni seguire i link qui sotto:<\/p>\n<ul>\n<li><a href=\"https:\/\/ambwashingtondc.esteri.it\/it\/servizi-consolari-e-visti\/servizi-per-il-cittadino-italiano\/traduzione-e-legalizzazione-dei-documenti\/le-legalizzazioni-di-documenti-tra-italia-ed-usa-lapostille\/\">Legalizzazione di documenti<\/a><\/li>\n<li><a href=\"https:\/\/ambwashingtondc.esteri.it\/it\/servizi-consolari-e-visti\/servizi-per-il-cittadino-italiano\/traduzione-e-legalizzazione-dei-documenti\/traduzioni-conformita\/\">Certificazione di conformit\u00e0 delle traduzioni<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><em>Ultimo aggiornamento: 1 maggio 2026<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"La nostra Cancelleria Consolare non effettua traduzioni. Spetta in genere agli utenti provvedere autonomamente a tradurre i documenti di loro interesse. La Cancelleria Consolare tuttavia, provvede a certificare la conformit\u00e0 agli originali delle traduzioni degli atti di stato civile e di vari altri documenti. Per un elenco non esclusivo di traduttori e interpreti a cui [&hellip;]","protected":false},"author":3,"featured_media":0,"parent":67,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-241","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ambwashingtondc.esteri.it\/it\/wp-json\/wp\/v2\/pages\/241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambwashingtondc.esteri.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ambwashingtondc.esteri.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ambwashingtondc.esteri.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ambwashingtondc.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=241"}],"version-history":[{"count":6,"href":"https:\/\/ambwashingtondc.esteri.it\/it\/wp-json\/wp\/v2\/pages\/241\/revisions"}],"predecessor-version":[{"id":16591,"href":"https:\/\/ambwashingtondc.esteri.it\/it\/wp-json\/wp\/v2\/pages\/241\/revisions\/16591"}],"up":[{"embeddable":true,"href":"https:\/\/ambwashingtondc.esteri.it\/it\/wp-json\/wp\/v2\/pages\/67"}],"wp:attachment":[{"href":"https:\/\/ambwashingtondc.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}